{"id":39303,"date":"2024-04-03T09:40:41","date_gmt":"2024-04-03T04:10:41","guid":{"rendered":"https:\/\/wadhwanifoundation.org\/?post_type=press&#038;p=39303"},"modified":"2024-04-16T09:45:47","modified_gmt":"2024-04-16T04:15:47","slug":"com-a-ajuda-de-um-vilao-ou-aliado","status":"publish","type":"press","link":"https:\/\/wadhwanifoundation.org\/pt\/press\/with-the-help-of-ai-villain-or-ally\/","title":{"rendered":"\"Com a ajuda da IA - vil\u00e3 ou aliada?\"\u00a0"},"content":{"rendered":"<div class='wp-block-pdfp-pdf-poster  alignnone' id='block-2'\n        data-attributes='{&quot;uniqueId&quot;:&quot;pdfp1&quot;,&quot;file&quot;:&quot;https:\\\/\\\/wadhwanifoundation.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Article_Wadhwani_EPOCA_Magazine.pdf&quot;,&quot;title&quot;:&quot;EPOCA_Magazine&quot;,&quot;height&quot;:{&quot;desktop&quot;:&quot;842px&quot;,&quot;tablet&quot;:&quot;700px&quot;,&quot;mobile&quot;:&quot;400px&quot;},&quot;width&quot;:{&quot;desktop&quot;:&quot;100%&quot;,&quot;tablet&quot;:&quot;100%&quot;,&quot;mobile&quot;:&quot;100%&quot;},&quot;print&quot;:false,&quot;showName&quot;:true,&quot;downloadButton&quot;:true,&quot;btnStyles&quot;:{&quot;background&quot;:&quot;#1e73be&quot;,&quot;color&quot;:&quot;#ffffff&quot;,&quot;fontSize&quot;:&quot;1rem&quot;,&quot;padding&quot;:{&quot;top&quot;:10,&quot;right&quot;:20,&quot;bottom&quot;:10,&quot;left&quot;:20}},&quot;socialShare&quot;:{&quot;enabled&quot;:false,&quot;facebook&quot;:true,&quot;twitter&quot;:true,&quot;linkedin&quot;:true,&quot;pinterest&quot;:true,&quot;mailto&quot;:true,&quot;position&quot;:&quot;top&quot;},&quot;fullscreenButton&quot;:false,&quot;fullscreenButtonText&quot;:&quot;View Fullscreen&quot;,&quot;newWindow&quot;:true,&quot;downloadButtonText&quot;:&quot;Download File&quot;,&quot;protect&quot;:false,&quot;onlyPDF&quot;:false,&quot;defaultBrowser&quot;:true,&quot;thumbMenu&quot;:true,&quot;initialPage&quot;:&quot;1&quot;,&quot;sidebarOpen&quot;:true,&quot;lastVersion&quot;:false,&quot;hrScroll&quot;:false,&quot;openLinksInNewTab&quot;:false,&quot;annotationMode&quot;:true,&quot;progressiveLoading&quot;:true,&quot;flipbookSound&quot;:true,&quot;keyboardNav&quot;:false,&quot;rtlMode&quot;:&quot;off&quot;,&quot;themeMode&quot;:&quot;light&quot;,&quot;flipbookSourceType&quot;:&quot;pdf&quot;,&quot;flipbookImages&quot;:[],&quot;watermark&quot;:{&quot;enabled&quot;:false},&quot;alert&quot;:false,&quot;popupOptions&quot;:{&quot;enabled&quot;:0,&quot;text&quot;:&quot;Open PDF&quot;,&quot;triggerType&quot;:&quot;button&quot;,&quot;image&quot;:&quot;&quot;,&quot;imageHeight&quot;:&quot;200px&quot;,&quot;imageWidth&quot;:&quot;300px&quot;,&quot;imagePdfIcon&quot;:true,&quot;triggerAlignment&quot;:&quot;center&quot;,&quot;btnStyle&quot;:{&quot;background&quot;:&quot;#1e73be&quot;,&quot;color&quot;:&quot;#ffffff&quot;,&quot;fontSize&quot;:&quot;1rem&quot;,&quot;padding&quot;:{&quot;top&quot;:10,&quot;right&quot;:20,&quot;bottom&quot;:10,&quot;left&quot;:20}}},&quot;actionsPosition&quot;:&quot;top&quot;,&quot;adobeEmbedder&quot;:&quot;default&quot;,&quot;align&quot;:&quot;none&quot;,&quot;alignment&quot;:&quot;left&quot;,&quot;titleFontSize&quot;:&quot;16px&quot;,&quot;isHideRightToolbar&quot;:false,&quot;additional&quot;:{&quot;ID&quot;:&quot;&quot;,&quot;Class&quot;:&quot;&quot;,&quot;CSS&quot;:&quot;&quot;},&quot;adobeOptions&quot;:{&quot;showDownloadPDF&quot;:true,&quot;showPrintPDF&quot;:true,&quot;showAnnotationTools&quot;:true,&quot;showFullScreen&quot;:false,&quot;embedMode&quot;:&quot;SIZED_CONTAINER&quot;},&quot;popupBtnStyle&quot;:{&quot;background&quot;:&quot;#2271b1&quot;,&quot;color&quot;:&quot;#fff&quot;,&quot;padding&quot;:{&quot;top&quot;:10,&quot;right&quot;:20,&quot;bottom&quot;:10,&quot;left&quot;:10}},&quot;popupBtnText&quot;:&quot;Open Document&quot;,&quot;CSS&quot;:&quot;&quot;,&quot;TrpContentRestriction&quot;:{&quot;restriction_type&quot;:&quot;exclude&quot;,&quot;selected_languages&quot;:[],&quot;panel_open&quot;:true},&quot;isPremium&quot;:true}'\n                data-pdfp-theme='light'                style=\"text-align: left\">\n                    <div class=\"pdfp_loading_placeholder\"\n                style=\"height: 842px; width: 100%; display: flex; align-items: center; justify-content: center; background: #f5f5f5; border: 1px solid #ddd;\">\n                <p>Loading Viewer...<\/p>\n            <\/div>\n            <\/div>\n\n\n\n\n<p class=\"wp-block-paragraph\">Iniciativas relacionadas ao uso de IA generativa aplicada ao desenvolvimento de habilidades humanas tamb\u00e9m est\u00e3o em andamento. Na Funda\u00e7\u00e3o Wadhwani, organiza\u00e7\u00e3o especializada na prepara\u00e7\u00e3o e reinser\u00e7\u00e3o de talentos no mercado de trabalho, os m\u00f3dulos de treinamento para professores e alunos come\u00e7aram a receber o apoio de co-pilotos de IA. Desenvolvidos a partir de grandes plataformas de modelos de linguagem (como Llama e ChatGPT-4), os assistentes digitais s\u00e3o aplicados em jornadas de habilidades socioemocionais, treinamento para entrevistas de emprego e prepara\u00e7\u00e3o de professores. A primeira vers\u00e3o foi lan\u00e7ada em outubro para um grupo inicial de 500 participantes - a previs\u00e3o \u00e9 chegar a 12.000 at\u00e9 o final do ano. \"Os usu\u00e1rios podem acessar tutores virtuais para fazer perguntas durante os m\u00f3dulos de aprendizagem. Em vez de formular solu\u00e7\u00f5es prontas, os sistemas priorizam respostas que levem os alunos a refletir sobre os assuntos apresentados nas plataformas\", diz Thiago Fran\u00e7oso, vice-presidente da Iniciativa de Empregabilidade da Wadhwani Foundation Brasil.\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>Os usu\u00e1rios podem acessar tutores virtuais para fazer perguntas durante os m\u00f3dulos de aprendizagem. Em vez de formular solu\u00e7\u00f5es prontas, os sistemas priorizam respostas que levem os alunos a refletir sobre as quest\u00f5es apresentadas nas plataformas<\/p>","protected":false},"author":81,"featured_media":39304,"template":"","tags":[5],"press-category":[],"coauthors":[184],"class_list":["post-39303","press","type-press","status-publish","has-post-thumbnail","hentry","tag-quote"],"acf":[],"_links":{"self":[{"href":"https:\/\/wadhwanifoundation.org\/pt\/wp-json\/wp\/v2\/press\/39303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wadhwanifoundation.org\/pt\/wp-json\/wp\/v2\/press"}],"about":[{"href":"https:\/\/wadhwanifoundation.org\/pt\/wp-json\/wp\/v2\/types\/press"}],"author":[{"embeddable":true,"href":"https:\/\/wadhwanifoundation.org\/pt\/wp-json\/wp\/v2\/users\/81"}],"version-history":[{"count":0,"href":"https:\/\/wadhwanifoundation.org\/pt\/wp-json\/wp\/v2\/press\/39303\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wadhwanifoundation.org\/pt\/wp-json\/wp\/v2\/media\/39304"}],"wp:attachment":[{"href":"https:\/\/wadhwanifoundation.org\/pt\/wp-json\/wp\/v2\/media?parent=39303"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wadhwanifoundation.org\/pt\/wp-json\/wp\/v2\/tags?post=39303"},{"taxonomy":"press-category","embeddable":true,"href":"https:\/\/wadhwanifoundation.org\/pt\/wp-json\/wp\/v2\/press-category?post=39303"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/wadhwanifoundation.org\/pt\/wp-json\/wp\/v2\/coauthors?post=39303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}